{"id":86,"date":"2015-06-19T06:54:32","date_gmt":"2015-06-19T06:54:32","guid":{"rendered":"http:\/\/www.der-pfau.de\/?p=86"},"modified":"2015-06-19T15:01:47","modified_gmt":"2015-06-19T15:01:47","slug":"lichtraumprofile","status":"publish","type":"post","link":"https:\/\/www.der-pfau.de\/index.php\/lichtraumprofile\/","title":{"rendered":"Lichtraumprofil \/ Herstellen von Durchfahrtsh\u00f6hen"},"content":{"rendered":"<p><a href=\"http:\/\/www.der-pfau.de\/wp-content\/uploads\/2012\/06\/Lichtraumprofil.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-full wp-image-701\" title=\"Lichtraumprofil\" alt=\"\" src=\"http:\/\/www.der-pfau.de\/wp-content\/uploads\/2012\/06\/Lichtraumprofil.jpg\" width=\"585\" height=\"150\" srcset=\"https:\/\/www.der-pfau.de\/wp-content\/uploads\/2012\/06\/Lichtraumprofil.jpg 585w, https:\/\/www.der-pfau.de\/wp-content\/uploads\/2012\/06\/Lichtraumprofil-300x76.jpg 300w, https:\/\/www.der-pfau.de\/wp-content\/uploads\/2012\/06\/Lichtraumprofil-500x128.jpg 500w\" sizes=\"auto, (max-width: 585px) 100vw, 585px\" \/><\/a><\/p>\n<p>Mit viel Gef\u00fchl n\u00e4hern wir uns bei altem Baumbestand Ihrer gew\u00fcnschten Durchfahrtsh\u00f6he an. Stark\u00e4ste sowie stammnahe \u00c4ste versuchen wir mit kreativen L\u00f6sungen zu erhalten.<\/p>\n<p><!--more--><\/p>\n<p>Hierzu ein interessanter Rechtsbeitrag von Ass. jur.\u00a0 Helge Breloer \u00fcber das Verh\u00e4ltnis Verkehrssicherungspflicht und\u00a0 Freischneiden des Lichtraumprofiles an \u00f6ffentlichen Stra\u00dfen. <a href=\"http:\/\/www.der-pfau.de\/wp-content\/uploads\/2012\/07\/Lichtraumprofil.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-full wp-image-918\" title=\"Lichtraumprofil\" alt=\"\" src=\"http:\/\/www.der-pfau.de\/wp-content\/uploads\/2012\/07\/Lichtraumprofil.jpg\" width=\"1000\" height=\"690\" srcset=\"https:\/\/www.der-pfau.de\/wp-content\/uploads\/2012\/07\/Lichtraumprofil.jpg 1000w, https:\/\/www.der-pfau.de\/wp-content\/uploads\/2012\/07\/Lichtraumprofil-300x207.jpg 300w, https:\/\/www.der-pfau.de\/wp-content\/uploads\/2012\/07\/Lichtraumprofil-768x530.jpg 768w, https:\/\/www.der-pfau.de\/wp-content\/uploads\/2012\/07\/Lichtraumprofil-435x300.jpg 435w, https:\/\/www.der-pfau.de\/wp-content\/uploads\/2012\/07\/Lichtraumprofil-434x300.jpg 434w\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\" \/><\/a><\/p>\n<table width=\"584\" border=\"0\" cellspacing=\"0\" cellpadding=\"2\">\n<tbody>\n<tr>\n<td width=\"612\">\n<p align=\"JUSTIFY\"><em><strong>Ein Urteil des Oberlandesgerichts (OLG) Dresden vom 2. Oktober 1996 &#8211; 6 U 321\/96 -(Stadt und Gr\u00fcn 1997 (10), 727) stellt grunds\u00e4tzlich klar, welche Anforderungen einerseits an das Freischneiden des Lichtraumprofils und andererseits an das Verhalten des Kraftfahrzeugfahrers auf Stra\u00dfen mit B\u00e4umen zu stellen sind.<\/strong><\/em><\/p>\n<p align=\"LEFT\"><strong>1. Kein Gesetz \u00fcber Lichtraumprofil<\/strong><\/p>\n<p align=\"JUSTIFY\">Es gibt keine gesetzliche Vorschrift, die das Lichtraumprofil ausdr\u00fccklich erw\u00e4hnt oder anordnet, dass die Kronen der Stra\u00dfenb\u00e4ume in einer bestimmten H\u00f6he \u00fcber der Fahrbahn zur\u00fcckzuschneiden sind. Die Pflicht zum Freischneiden des Luftraums \u00fcber den Stra\u00dfen folgt daraus, dass nach \u00a7 32 Abs.1 Nr. 2 StVZO im Stra\u00dfenverkehr Fahrzeuge bis zu 4 m H\u00f6he zugelassen sind und diesen Fahrzeugen folglich ein gefahrloses Befahren der Stra\u00dfen erm\u00f6glicht werden muss. Dabei entspricht die \u00f6ffentlich &#8211; rechtliche gestaltete Amtspflicht zur Sorge f\u00fcr die Verkehrssicherheit inhaltlich der allgemeinen Verkehrssicherungspflicht. Diese umfasst neben den notwendigen Ma\u00dfnahmen zur Herbeif\u00fchrung und Erhaltung eines f\u00fcr den Stra\u00dfenbenutzer hinreichend sicheren Stra\u00dfenzustands auch die Freihaltung des Luftraums \u00fcber der Stra\u00dfe von hereinragenden \u00c4sten.<\/p>\n<p align=\"LEFT\"><strong>2. Umfang der Pflicht zum Freischneiden des Lichtraumprofils<\/strong><\/p>\n<p align=\"JUSTIFY\">Die allgemeinen Grunds\u00e4tze \u00fcber die Verkehrssicherungspflicht an Stra\u00dfen haben sowohl der Bundesgerichtshof1) wie auch mehrere Oberlandesgerichte2) hinsichtlich der Einhaltung des Lichtraumprofils dahingehend ausgelegt, dass es die Verkehrssicherungspflicht nicht erfordert, den Luftraum \u00fcber Stra\u00dfen generell in der nach \u00a7 32 Abs.1 Nr.2 StVZO f\u00fcr Fahrzeuge geltenden maximalen H\u00f6he von 4 m freizuhalten.<\/p>\n<p align=\"JUSTIFY\">Das OLG Dresden legt sich in seinen Entscheidungsgr\u00fcnden nicht auf die letztlich erforderliche H\u00f6he mit Zahlenangaben fest. Es steht an keiner Stelle, dass f\u00fcr das Lichtraumprofil beispielsweise bis zu einer H\u00f6he von 4,5 m \u00c4ste entfernt werden m\u00fcssen. Es hei\u00dft nur, dass ein Fahrzeug mit 4 m H\u00f6he die Stra\u00dfe gefahrlos benutzen k\u00f6nnen muss. <em>&#8222;Bis zu welcher H\u00f6he der Verkehrsraum von hereinragenden \u00c4sten freizuhalten ist, h\u00e4ngt vielmehr von der Verkehrsbedeutung der Stra\u00dfe ab. Ihre Verkehrssicherheit und das \u00f6kologische Interesse an der Erhaltung alten Baumbestands sind gegeneinander abzuw\u00e4gen.&#8220;<\/em><\/p>\n<p align=\"LEFT\"><strong>3. Das \u00f6kologische Interesse an der Erhaltung des Baumbestands<\/strong><\/p>\n<p align=\"JUSTIFY\">Das Umweltbewusstsein hat auch in der Rechtsprechung seinen Niederschlag gefunden. Der Hinweis auf die Abw\u00e4gung zwischen Verkehrssicherheit und dem Interesse an der Baumerhaltung ist seit 1992 in der Rechtsprechung zur Verkehrssicherungspflicht f\u00fcr B\u00e4ume zu finden. So hatte sich beispielsweise das OLG Hamm3) mit einem Unfall zu befassen, bei dem ein Wohnmobil mit seinen Aufbauten gegen einen in 3,6 m H\u00f6he in die Fahrbahn geneigten Platanenstamm gefahren war. In den Urteilsgr\u00fcnden hei\u00dft es auch:<br \/>\n<em>&#8222;Wie in den letzten Jahren zunehmend in das allgemeine Bewusstsein gedrungen ist, besteht an der Erhaltung des Baumbestands auch an \u00f6ffentlichen Stra\u00dfen ein allgemeines Interesse, so dass zwischen den Belangen der Verkehrssicherheit und den \u00f6kologischen Interessen an der Erhaltung des Baumbestands abzuw\u00e4gen ist.<br \/>\nHierbei ist den \u00f6kologischen Interessen an Stra\u00dfen von nur geringer Verkehrsbedeutung in h\u00f6herem Ma\u00df Rechnung zu tragen, als den Stra\u00dfen von erheblicher Verkehrsbedeutung &#8230; Bestimmend f\u00fcr die Verkehrsbedeutung sind die Umst\u00e4nde des Einzelfalls, die Art und das Ma\u00df der Verkehrssicherungspflicht nach den gegebenen Verkehrsverh\u00e4ltnissen wie nach der Art des Wegs, seiner Verkehrswichtigkeit, der Gr\u00f6\u00dfe einer Ortschaft und \u00e4hnlichem festlegen.&#8220;<\/em><\/p>\n<p align=\"LEFT\"><em><strong>4. Die Anhaltepflicht des Kraftfahrers<\/strong><\/em><\/p>\n<p align=\"JUSTIFY\"><em>Das Schleswig-Holsteinische OLG hatte in einem Urteil vom 7. April 19934) ebenso argumentiert. Es ging in dem zugrundeliegenden Rechtsstreit um einen Lkw &#8211; Fahrer, der in einem Wohngebiet gegen den unterhalb von 4 m H\u00f6he in die Fahrbahn ragenden Ast gefahren war. Hier hatte das Gericht verlangt, dass der Fahrer notfalls h\u00e4tte anhalten m\u00fcssen, wenn die Stra\u00dfe bei entgegenkommendem Verkehr nicht breit genug zum Ausweichen gewesen sei. Das OLG Dresden hat im vorliegenden Fall diese Anhaltepflicht sogar dem Kraftfahrzeugf\u00fchrer auf einer Bundesstra\u00dfe auferlegt. Er h\u00e4tte, &#8222;wenn er wegen des Gegenverkehrs an dem Baum nicht mehr mit einem ausreichendem Abstand vorbeifahren konnte, vorher anhalten m\u00fcssen, um den grob sorgfaltswidrig handelnden \u00dcberholer passieren zu lassen.&#8220;<br \/>\nDas OLG Dresden sah ein Mitverschulden in dem Nichthalten und rechnete auch die durch den hohen Aufbau des Lkw gesteigerte Betriebsgefahr hinzu, so dass sich der geltend gemachte Schadensersatzanspruch letztlich um 50 % minderte. Der Zivilprozess ist ein Beweisprozess. Insofern hat sich der Lkw-Fahrer, wenn er sich entlasten will, nachzuweisen, dass er dem in die Fahrbahn ragenden Ast nicht ausweichen und nicht anhalten konnte. Die Rechtsprechung geht grunds\u00e4tzlich davon aus, dass derjenige, der auf ein Hindernis auff\u00e4hrt, entweder zu schnell oder unaufmerksam gefahren ist. Die Grundlagen einer solchen tats\u00e4chlichen Vermutung muss der mit einem in die Fahrbahn ragenden Ast kollidierende Kfz-Fahrer ersch\u00fcttern, das hei\u00dft er muss in diesem Ausnahmefall seine Unschuld beweisen.<\/em><\/p>\n<p align=\"LEFT\"><em><strong>5. Die Pflicht zum Freischneiden des Lichtraumprofils an Bundesstra\u00dfen und Ausfallstra\u00dfen<\/strong><\/em><\/p>\n<p align=\"JUSTIFY\"><em>Das Mitverschulden des Gesch\u00e4digten kann in einem unterschiedlichen Prozentsatz seinen Schadensersatzanspruch mindern, es enthebt den Baumeigent\u00fcmer aber nicht von seiner grunds\u00e4tzlichen Verkehrssicherungspflicht hinsichtlich des Lichtraumprofils. Diese Verkehrssicherungspflicht wiederum beinhaltet nicht notwendigerweise, dass der Luftraum an allen Stra\u00dfen gleicherma\u00dfen v\u00f6llig in der f\u00fcr Fahrzeuge mit Maximalabmessungen notwendigen H\u00f6he freizuhalten ist. Mit zunehmendem Verkehrsaufkommen sind aber strengere Ma\u00dfst\u00e4be an die Verkehrssicherungspflicht anzulegen. Dazu f\u00fchrt das OLG Dresden aus:<br \/>\n&#8222;Bei Stra\u00dfen von erheblicher Verkehrsbedeutung, namentlich Bundesstra\u00dfen und Ausfallstra\u00dfen &#8230; erscheint es im Interesse der Verkehrssicherheit und des Schutzes der Rechtsg\u00fcter der Verkehrsteilnehmer unabweislich, dass der Verkehrsraum in dem Umfang, in dem er von Fahrzeugen mit den gesetzlich maximal zul\u00e4ssigen Abmessungen in Anspruch genommen werden kann, von B\u00e4umen und \u00c4sten ebenso wie von sonstigen st\u00f6renden Einfl\u00fcssen freigehalten wird &#8230; Dieser Schutz gilt f\u00fcr den Luftraum (,Lichtraum&#8216;) \u00fcber der Fahrbahn, wobei der Lichtraum \u00fcber der Fahrbahngrenze nicht lotrecht, sondern nach dem Winkel zu ermitteln ist, &#8230; so dass auch der \u00fcber dem \u00e4u\u00dferen rechten, nur noch vom Bordstein begrenzte Fahrbahnrand gelegene Luftraum verkehrsicherungspflichtig ist.&#8220;<br \/>\nDiese Feststellung des Gerichts ist f\u00fcr die Praxis beim Freischneiden des Lichtraumprofils, das hei\u00dft f\u00fcr die dabei vorzunehmenden Abmessungen, von Bedeutung.<\/em><\/p>\n<p align=\"LEFT\"><em><strong>6. Verkehrszeichen zum eingeschr\u00e4nkten Lichtraumprofil entbinden nicht von der Haftung<\/strong><\/em><\/p>\n<p align=\"JUSTIFY\"><em>Beachtung verdient auch die nur in einem Nebensatz enthaltende Klarstellung des OLG Dresden, dass Warnschilder mit Hinweis auf ein eingeschr\u00e4nktes Lichtraumprofil, wie sie durch die StVZO zugelassen sind, nicht geeignet sind, die Haftung des Baumeigent\u00fcmers f\u00fcr in die Fahrbahn hineinragende \u00c4ste auszuschlie\u00dfen. Das wird vielfach angenommen, weil Gerichte hier ein Mitverschulden des Kfz-Fahrers &#8211; je nach Fallgestaltung &#8211; angenommen haben. Aber allein durch Hinweisschilder l\u00e4sst sich grunds\u00e4tzlich keine Haftung ausschlie\u00dfen, sondern der Umfang der Haftung kann unter Umst\u00e4nden eingeschr\u00e4nkt werden. Das gilt in anderen F\u00e4llen der Verkehrssicherungspflicht ebenso f\u00fcr das Schild &#8222;Betreten auf eigene Gefahr&#8220; wie f\u00fcr andere Hinweisschilder auf m\u00f6gliche Gefahren.<br \/>\nAllerdings, so f\u00fchrt das OLG Dresden mit Blick hier auf die B\u00e4ume an Bundesstra\u00dfen aus, &#8222;gelten f\u00fcr \u00dcberf\u00fchrungen mit niedrigen Durchfahrten insoweit Besonderheiten, weil sie deutlicher wahrnehmbar sind und weil vor ihnen auf leichtere und wirkungsvollere Art, n\u00e4mlich durch Anbringen von Markierungen und Ma\u00dfgaben gewarnt werden kann. Bei B\u00e4umen bleibt dagegen, weil Hinweise durch Warnschilder nicht ausreichen (OLG K\u00f6ln a.a.O., BGH VersR 1968, 73) und fahrbahnbeschr\u00e4nkende Ma\u00dfnahmen regelm\u00e4\u00dfig ausscheiden, als einziges Mittel die Entfernung des Hindernisses&#8220;.<br \/>\nDas OLG Dresden, das offensichtlich falsche Schlussfolgerungen bef\u00fcrchtete, sah sich sofort im Anschluss an diese Feststellung in den Urteilsgr\u00fcnden zu dem Hinweis veranlasst: &#8222;Der Senat weist ausdr\u00fccklich darauf hin, dass zur Beachtung der Verkehrssicherungspflicht des ,Lichtraums&#8216; ein generelles F\u00e4llen von Alleeb\u00e4umen &#8211; auch entlang von Bundesstra\u00dfen &#8211; nicht erforderlich ist.&#8220;<\/em><\/p>\n<table width=\"534\" border=\"0\" cellspacing=\"0\" cellpadding=\"2\">\n<colgroup>\n<col width=\"33\" \/>\n<col width=\"493\" \/><\/colgroup>\n<tbody>\n<tr>\n<td valign=\"TOP\" width=\"33\"><span style=\"font-family: Arial,Helvetica,sans-serif;\"><span style=\"font-size: xx-small;\">1<\/span><\/span><\/td>\n<td width=\"493\"><span style=\"font-family: Arial,Helvetica,sans-serif;\"><span style=\"font-size: xx-small;\">BGH I.M 823 &#8211; EA &#8211; BGB Nr. 16; BGH VersR 1968, 72; BGHZ 60,54.<\/span><\/span><\/td>\n<\/tr>\n<tr>\n<td valign=\"TOP\" width=\"33\"><span style=\"font-family: Arial,Helvetica,sans-serif;\"><span style=\"font-size: xx-small;\">2<\/span><\/span><\/td>\n<td width=\"493\"><span style=\"font-family: Arial,Helvetica,sans-serif;\"><span style=\"font-size: xx-small;\">KG VersR 1971,183; OLG M\u00fcnchen VersR1988,859; OLG D\u00fcsseldorf VersR 1989, 273; OLG K\u00f6ln VersR 1991, 1206<\/span><\/span><\/td>\n<\/tr>\n<tr>\n<td valign=\"TOP\" width=\"33\"><span style=\"font-family: Arial,Helvetica,sans-serif;\"><span style=\"font-size: xx-small;\">3<\/span><\/span><\/td>\n<td width=\"493\"><span style=\"font-family: Arial,Helvetica,sans-serif;\"><span style=\"font-size: xx-small;\">OLG Hamm VersR 1995, 1206<\/span><\/span><\/td>\n<\/tr>\n<tr>\n<td valign=\"TOP\" width=\"33\"><span style=\"font-family: Arial,Helvetica,sans-serif;\"><span style=\"font-size: xx-small;\">4<\/span><\/span><\/td>\n<td width=\"493\"><span style=\"font-family: Arial,Helvetica,sans-serif;\"><span style=\"font-size: xx-small;\">OLG Schleswig VersR 1994, 359<\/span><\/span><\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Mit viel Gef\u00fchl n\u00e4hern wir uns bei altem Baumbestand Ihrer gew\u00fcnschten Durchfahrtsh\u00f6he an. Stark\u00e4ste sowie stammnahe \u00c4ste versuchen wir mit kreativen L\u00f6sungen zu erhalten.<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[6],"tags":[333,281,74,295,336],"class_list":["post-86","post","type-post","status-publish","format-standard","hentry","category-pflegemassnahmen","tag-ammersee-baumpflege","tag-baumkontrolleur-fll-zertifiziert","tag-baumpflege-am-ammersee","tag-baumpflege-utting","tag-utting-baumpflege"],"_links":{"self":[{"href":"https:\/\/www.der-pfau.de\/index.php\/wp-json\/wp\/v2\/posts\/86","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.der-pfau.de\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.der-pfau.de\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.der-pfau.de\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.der-pfau.de\/index.php\/wp-json\/wp\/v2\/comments?post=86"}],"version-history":[{"count":21,"href":"https:\/\/www.der-pfau.de\/index.php\/wp-json\/wp\/v2\/posts\/86\/revisions"}],"predecessor-version":[{"id":913,"href":"https:\/\/www.der-pfau.de\/index.php\/wp-json\/wp\/v2\/posts\/86\/revisions\/913"}],"wp:attachment":[{"href":"https:\/\/www.der-pfau.de\/index.php\/wp-json\/wp\/v2\/media?parent=86"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.der-pfau.de\/index.php\/wp-json\/wp\/v2\/categories?post=86"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.der-pfau.de\/index.php\/wp-json\/wp\/v2\/tags?post=86"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}