{"id":82,"date":"2012-06-05T06:54:04","date_gmt":"2012-06-05T06:54:04","guid":{"rendered":"http:\/\/www.der-pfau.de\/?p=82"},"modified":"2015-06-05T16:10:25","modified_gmt":"2015-06-05T16:10:25","slug":"totholzentfernung","status":"publish","type":"post","link":"https:\/\/www.der-pfau.de\/index.php\/totholzentfernung\/","title":{"rendered":"Entfernung von abgestorbenen \u00c4sten \/ Totholzentfernung"},"content":{"rendered":"<p><a href=\"http:\/\/www.der-pfau.de\/wp-content\/uploads\/2012\/06\/Totholzentfernung.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-full wp-image-755\" title=\"Totholzentfernung\" alt=\"\" src=\"http:\/\/www.der-pfau.de\/wp-content\/uploads\/2012\/06\/Totholzentfernung.jpg\" width=\"585\" height=\"150\" srcset=\"https:\/\/www.der-pfau.de\/wp-content\/uploads\/2012\/06\/Totholzentfernung.jpg 585w, https:\/\/www.der-pfau.de\/wp-content\/uploads\/2012\/06\/Totholzentfernung-300x76.jpg 300w, https:\/\/www.der-pfau.de\/wp-content\/uploads\/2012\/06\/Totholzentfernung-500x128.jpg 500w\" sizes=\"auto, (max-width: 585px) 100vw, 585px\" \/><\/a><\/p>\n<p>Wir entfernen an Stra\u00dfen, in \u00f6ffentlichen Gr\u00fcnfl\u00e4chen, auf Parkpl\u00e4tzen, in Bierg\u00e4rten, usw., schnell und zuverl\u00e4ssig abgestorbene, trockene, abbruchgef\u00e4hrdete \u00c4ste.<\/p>\n<p><!--more--> Eine \u201eformularm\u00e4\u00dfige Freizeichnung\u201c\u00a0 durch Beschilderung wie z.B. <em>&#8220; Achtung herabfallende \u00c4ste<\/em> &#8220; ist nicht m\u00f6glich, wenn abgestorbene \u00c4ste auf einen Verkehrsweg st\u00fcrzen k\u00f6nnten. Bereiche mit Totholz in der Baumkrone k\u00f6nnen nur dadurch entsch\u00e4rft werden, indem das \u00c4ste entnommen, oder das Baumumfeld f\u00fcr den \u00f6ffentlichen Verkehr wirksam gesperrt wird.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Wir entfernen an Stra\u00dfen, in \u00f6ffentlichen Gr\u00fcnfl\u00e4chen, auf Parkpl\u00e4tzen, in Bierg\u00e4rten, usw., schnell und zuverl\u00e4ssig abgestorbene, trockene, abbruchgef\u00e4hrdete \u00c4ste.<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[6],"tags":[60,310,345,294,70,63,74,295,132],"class_list":["post-82","post","type-post","status-publish","format-standard","hentry","category-pflegemassnahmen","tag-ammersee","tag-baum-fallen-utting","tag-artenschutz","tag-baume-unser-handwerk","tag-baumkontrolle","tag-baumpflege","tag-baumpflege-am-ammersee","tag-baumpflege-utting","tag-totholz"],"_links":{"self":[{"href":"https:\/\/www.der-pfau.de\/index.php\/wp-json\/wp\/v2\/posts\/82","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.der-pfau.de\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.der-pfau.de\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.der-pfau.de\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.der-pfau.de\/index.php\/wp-json\/wp\/v2\/comments?post=82"}],"version-history":[{"count":19,"href":"https:\/\/www.der-pfau.de\/index.php\/wp-json\/wp\/v2\/posts\/82\/revisions"}],"predecessor-version":[{"id":2048,"href":"https:\/\/www.der-pfau.de\/index.php\/wp-json\/wp\/v2\/posts\/82\/revisions\/2048"}],"wp:attachment":[{"href":"https:\/\/www.der-pfau.de\/index.php\/wp-json\/wp\/v2\/media?parent=82"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.der-pfau.de\/index.php\/wp-json\/wp\/v2\/categories?post=82"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.der-pfau.de\/index.php\/wp-json\/wp\/v2\/tags?post=82"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}